{"id":8687,"date":"2023-08-22T03:00:55","date_gmt":"2023-08-22T03:00:55","guid":{"rendered":"http:\/\/timeline-kreuznach.de\/pol-pdmt-unerlaubtes-entfernen-vom-unfallort-in-bad-marienberg"},"modified":"2023-08-22T03:00:55","modified_gmt":"2023-08-22T03:00:55","slug":"pol-pdmt-unerlaubtes-entfernen-vom-unfallort-in-bad-marienberg","status":"publish","type":"post","link":"https:\/\/timeline-kreuznach.de\/en\/pol-pdmt-unerlaubtes-entfernen-vom-unfallort-in-bad-marienberg","title":{"rendered":"POL-PDMT: Unauthorized removal from the scene of an accident in Bad Marienberg"},"content":{"rendered":"<div><b>Polizeidirektion Montabaur<\/b> [<a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117710\/5585252\">Newsroom<\/a>]<br \/>Montabaur (ots) &#8211; Am 20.08.2023 ereignete sich zwischen 14:30 Uhr und 16:45 Uhr auf dem Parkplatz in der Albrechtstra\u00dfe in Bad Marienberg (gegen\u00fcber Hausnummer 1) ein Verkehrsunfall mit Sachschaden. Hierbei wurde ein geparkter, beiger VW Caddy an &#8230; <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117710\/5585252\">Lesen Sie hier weiter&#8230;<\/a><br clear=\"all\"><\/p>\n<p><small>Original-Content von: Polizeidirektion Montabaur, \u00fcbermittelt durch news aktuell<\/small><\/p>\n<\/div>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polizeidirektion Montabaur [Newsroom]Montabaur (ots) &#8211; Am 20.08.2023 ereignete sich zwischen 14:30 Uhr und 16:45 Uhr auf dem Parkplatz in der Albrechtstra\u00dfe in Bad Marienberg (gegen\u00fcber Hausnummer 1) ein Verkehrsunfall mit Sachschaden. Hierbei wurde ein geparkter, beiger VW Caddy an &#8230; Lesen Sie hier weiter&#8230; Original-Content von: Polizeidirektion Montabaur, \u00fcbermittelt durch news aktuell Powered by WPeMatico<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8687","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/8687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/comments?post=8687"}],"version-history":[{"count":0,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/8687\/revisions"}],"wp:attachment":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/media?parent=8687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/categories?post=8687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/tags?post=8687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}