{"id":8333,"date":"2023-05-30T03:00:54","date_gmt":"2023-05-30T03:00:54","guid":{"rendered":"http:\/\/timeline-kreuznach.de\/pol-pikir-verkehrsunfall-unter-alkoholeinfluss"},"modified":"2023-05-30T03:00:54","modified_gmt":"2023-05-30T03:00:54","slug":"pol-pikir-verkehrsunfall-unter-alkoholeinfluss","status":"publish","type":"post","link":"https:\/\/timeline-kreuznach.de\/en\/pol-pikir-verkehrsunfall-unter-alkoholeinfluss","title":{"rendered":"POL-PIKIR: Traffic accident under the influence of alcohol"},"content":{"rendered":"<div><b>Polizeiinspektion Kirn<\/b> [<a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/131677\/5520212\">Newsroom<\/a>]<br \/>Hochstetten-Dhaun (ots) &#8211; Am 30.05.2023 kam gegen 00:18 Uhr ein 39-j\u00e4hriger Mann mit seinem PKW an der Einm\u00fcndung der B41 zur L183 aufgrund \u00fcberh\u00f6hter Geschwindigkeit von der Fahrbahn ab und \u00fcberschlug sich. Der Fahrer verletzte sich bei dem &#8230; <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/131677\/5520212\">Lesen Sie hier weiter&#8230;<\/a><br clear=\"all\"><\/p>\n<p><small>Original-Content von: Polizeiinspektion Kirn, \u00fcbermittelt durch news aktuell<\/small><\/p>\n<\/div>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polizeiinspektion Kirn [Newsroom]Hochstetten-Dhaun (ots) &#8211; Am 30.05.2023 kam gegen 00:18 Uhr ein 39-j\u00e4hriger Mann mit seinem PKW an der Einm\u00fcndung der B41 zur L183 aufgrund \u00fcberh\u00f6hter Geschwindigkeit von der Fahrbahn ab und \u00fcberschlug sich. Der Fahrer verletzte sich bei dem &#8230; Lesen Sie hier weiter&#8230; Original-Content von: Polizeiinspektion Kirn, \u00fcbermittelt durch news aktuell Powered by [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8333","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/8333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/comments?post=8333"}],"version-history":[{"count":0,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/8333\/revisions"}],"wp:attachment":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/media?parent=8333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/categories?post=8333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/tags?post=8333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}