{"id":7432,"date":"2022-11-29T03:01:02","date_gmt":"2022-11-29T03:01:02","guid":{"rendered":"http:\/\/timeline-kreuznach.de\/pol-pdtr-verkehrsunfallflucht-elisabeth-stiftung-birkenfeld"},"modified":"2022-11-29T03:01:02","modified_gmt":"2022-11-29T03:01:02","slug":"pol-pdtr-verkehrsunfallflucht-elisabeth-stiftung-birkenfeld","status":"publish","type":"post","link":"https:\/\/timeline-kreuznach.de\/en\/pol-pdtr-verkehrsunfallflucht-elisabeth-stiftung-birkenfeld","title":{"rendered":"POL-PDTR: Hit-and-run accident Elisabeth Stiftung Birkenfeld"},"content":{"rendered":"<div><b>Polizeidirektion Trier<\/b> [<a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117698\/5381739\">Newsroom<\/a>]<br \/>Birkenfeld (ots) &#8211; Am Montag, den 28.11.2022, in der Zeit von 07:00 Uhr bis 16: 35 Uhr, ereignete sich auf dem Parkplatz der Elisabeth Stiftung in Birkenfeld eine Verkehrsunfallflucht. Hier hat ein PKW beim Ausparken aus einer Parkl\u00fccke einen &#8230; <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117698\/5381739\">Lesen Sie hier weiter&#8230;<\/a><br clear=\"all\"><\/p>\n<p><small>Original-Content von: Polizeidirektion Trier, \u00fcbermittelt durch news aktuell<\/small><\/p>\n<\/div>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polizeidirektion Trier [Newsroom]Birkenfeld (ots) &#8211; Am Montag, den 28.11.2022, in der Zeit von 07:00 Uhr bis 16: 35 Uhr, ereignete sich auf dem Parkplatz der Elisabeth Stiftung in Birkenfeld eine Verkehrsunfallflucht. Hier hat ein PKW beim Ausparken aus einer Parkl\u00fccke einen &#8230; Lesen Sie hier weiter&#8230; Original-Content von: Polizeidirektion Trier, \u00fcbermittelt durch news aktuell Powered [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7432","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/comments?post=7432"}],"version-history":[{"count":0,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7432\/revisions"}],"wp:attachment":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/media?parent=7432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/categories?post=7432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/tags?post=7432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}