{"id":7241,"date":"2022-10-26T03:01:00","date_gmt":"2022-10-26T03:01:00","guid":{"rendered":"http:\/\/timeline-kreuznach.de\/pol-pdwil-sonderbares-ereignis-in-kroev"},"modified":"2022-10-26T03:01:00","modified_gmt":"2022-10-26T03:01:00","slug":"pol-pdwil-sonderbares-ereignis-in-kroev","status":"publish","type":"post","link":"https:\/\/timeline-kreuznach.de\/en\/pol-pdwil-sonderbares-ereignis-in-kroev","title":{"rendered":"POL-PDWIL: Strange event in Kr\u00f6v"},"content":{"rendered":"<div><b>Polizeidirektion Wittlich<\/b> [<a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117697\/5353882\">Newsroom<\/a>]<br \/>Kr\u00f6v (ots) &#8211; Nach einer Feierlichkeit am Abend des 21.10.2022 in der Weinbrunnenhalle in Kr\u00f6v suchte ein Besucher mit seiner Reisegruppe gegen Mitternacht das gemeinsame Hotel in der Robert-Schuman-Stra\u00dfe auf. Der Besucher verweilte noch einige &#8230; <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117697\/5353882\">Lesen Sie hier weiter&#8230;<\/a><br clear=\"all\"><\/p>\n<p><small>Original-Content von: Polizeidirektion Wittlich, \u00fcbermittelt durch news aktuell<\/small><\/p>\n<\/div>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polizeidirektion Wittlich [Newsroom]Kr\u00f6v (ots) &#8211; Nach einer Feierlichkeit am Abend des 21.10.2022 in der Weinbrunnenhalle in Kr\u00f6v suchte ein Besucher mit seiner Reisegruppe gegen Mitternacht das gemeinsame Hotel in der Robert-Schuman-Stra\u00dfe auf. Der Besucher verweilte noch einige &#8230; Lesen Sie hier weiter&#8230; Original-Content von: Polizeidirektion Wittlich, \u00fcbermittelt durch news aktuell Powered by WPeMatico<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7241","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/comments?post=7241"}],"version-history":[{"count":0,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7241\/revisions"}],"wp:attachment":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/media?parent=7241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/categories?post=7241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/tags?post=7241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}