{"id":7133,"date":"2022-10-05T03:01:51","date_gmt":"2022-10-05T03:01:51","guid":{"rendered":"http:\/\/timeline-kreuznach.de\/5335482-2"},"modified":"2022-10-05T03:01:51","modified_gmt":"2022-10-05T03:01:51","slug":"5335482-2","status":"publish","type":"post","link":"https:\/\/timeline-kreuznach.de\/en\/5335482-2","title":{"rendered":"POL-PDKH: Further wave of fraudulent shock calls from alleged relatives or police officers"},"content":{"rendered":"<div><b>Polizeidirektion Bad Kreuznach<\/b> [<a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117703\/5335482\">Newsroom<\/a>]<br \/>Bad Kreuznach (ots) &#8211; Bei der Kriminalpolizei Bad Kreuznach gehen zurzeit wieder Anzeigen von Gesch\u00e4digten ein, welche Anrufe von vermeintlichen Betr\u00fcgern erhalten haben. Die Masche der T\u00e4ter variiert leicht, hat jedoch grunds\u00e4tzlich einen &#8230; <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/117703\/5335482\">Lesen Sie hier weiter&#8230;<\/a><br clear=\"all\"><\/p>\n<p><small>Original-Content von: Polizeidirektion Bad Kreuznach, \u00fcbermittelt durch news aktuell<\/small><\/p>\n<\/div>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polizeidirektion Bad Kreuznach [Newsroom]Bad Kreuznach (ots) &#8211; Bei der Kriminalpolizei Bad Kreuznach gehen zurzeit wieder Anzeigen von Gesch\u00e4digten ein, welche Anrufe von vermeintlichen Betr\u00fcgern erhalten haben. Die Masche der T\u00e4ter variiert leicht, hat jedoch grunds\u00e4tzlich einen &#8230; Lesen Sie hier weiter&#8230; Original-Content von: Polizeidirektion Bad Kreuznach, \u00fcbermittelt durch news aktuell Powered by WPeMatico<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[8],"class_list":["post-7133","post","type-post","status-publish","format-standard","hentry","category-presseportal","tag-presseportal"],"_links":{"self":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/comments?post=7133"}],"version-history":[{"count":0,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/posts\/7133\/revisions"}],"wp:attachment":[{"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/media?parent=7133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/categories?post=7133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timeline-kreuznach.de\/en\/wp-json\/wp\/v2\/tags?post=7133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}